{"id":10740,"date":"2025-02-02T23:04:42","date_gmt":"2025-02-02T23:04:42","guid":{"rendered":"https:\/\/urica.org\/?p=10740"},"modified":"2025-02-02T23:05:16","modified_gmt":"2025-02-02T23:05:16","slug":"wilderness-ou-lerosion-systemique-de-lecologie-et-paysage-culturel-afro-americains-en-caroline-du-sud","status":"publish","type":"post","link":"https:\/\/urica.org\/index.php\/2025\/02\/02\/wilderness-ou-lerosion-systemique-de-lecologie-et-paysage-culturel-afro-americains-en-caroline-du-sud\/","title":{"rendered":"\u2018Wilderness\u2019 ou l\u2019\u00e9rosion syst\u00e9mique de l\u2019\u00e9cologie et paysage culturel Afro-Am\u00e9ricains en Caroline du Sud"},"content":{"rendered":"<p>L\u2019URICA a le plaisir de vous inviter \u00e0 son prochain webinaire, le <strong>mercredi 05 f\u00e9vrier<\/strong> \u00e0 partir de 15h30, intitul\u00e9\u00a0:\u00a0<strong>\u00ab <\/strong><strong>\u2018Wilderness\u2019 ou l\u2019\u00e9rosion syst\u00e9mique de l\u2019\u00e9cologie et paysage culturel Afro-Am\u00e9ricains en Caroline du Sud <\/strong><strong>\u00bb. <\/strong>Ce webinaire sera anim\u00e9 par<strong> Dr Aby L. S\u00e8ne<\/strong>, Professeur assistant \u00e0 Clemson University aux \u00c9tats Unis.<\/p>\n<p>Sa pr\u00e9sentation portera sur une partie d\u2019un projet de recherche qu\u2019elle m\u00e8ne en collaboration avec des chercheurs de l\u2019Aldo Leopold Wilderness Research Institute et d&rsquo;American Rivers. En utilisant la pratique du bricolage pour tisser ensemble diverses histoires li\u00e9es aux for\u00eats et marais c\u00f4tiers en Caroline du Sud, elle s&rsquo;appuie sur la litt\u00e9rature existante, les histoires orales et d\u2019autres documents historiques pour contextualiser les \u00e9cologies locales dans les processus d&rsquo;accumulation primitive qui font partie int\u00e9grante des formations capitalistes coloniales du pass\u00e9 et du pr\u00e9sent.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019URICA a le plaisir de vous inviter \u00e0 son prochain webinaire, le mercredi 05 f\u00e9vrier \u00e0 partir de 15h30, intitul\u00e9\u00a0:\u00a0\u00ab \u2018Wilderness\u2019 ou l\u2019\u00e9rosion syst\u00e9mique de l\u2019\u00e9cologie et paysage culturel Afro-Am\u00e9ricains&hellip;<\/p>\n","protected":false},"author":4,"featured_media":10738,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1,36],"tags":[],"class_list":["post-10740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe","category-webinaires"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/urica.org\/wp-content\/uploads\/2025\/02\/Aby-L.-Sene-scaled.jpg?fit=2560%2C1280&ssl=1","_links":{"self":[{"href":"https:\/\/urica.org\/index.php\/wp-json\/wp\/v2\/posts\/10740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urica.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urica.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urica.org\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/urica.org\/index.php\/wp-json\/wp\/v2\/comments?post=10740"}],"version-history":[{"count":1,"href":"https:\/\/urica.org\/index.php\/wp-json\/wp\/v2\/posts\/10740\/revisions"}],"predecessor-version":[{"id":10741,"href":"https:\/\/urica.org\/index.php\/wp-json\/wp\/v2\/posts\/10740\/revisions\/10741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/urica.org\/index.php\/wp-json\/wp\/v2\/media\/10738"}],"wp:attachment":[{"href":"https:\/\/urica.org\/index.php\/wp-json\/wp\/v2\/media?parent=10740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urica.org\/index.php\/wp-json\/wp\/v2\/categories?post=10740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urica.org\/index.php\/wp-json\/wp\/v2\/tags?post=10740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}